{"id":8937,"date":"2023-11-11T08:17:08","date_gmt":"2023-11-11T07:17:08","guid":{"rendered":"https:\/\/www.mostradelgelato.com\/?p=8937"},"modified":"2023-11-11T08:17:08","modified_gmt":"2023-11-11T07:17:08","slug":"dalla-spagna-un-educational-inedito-con-mig-2023","status":"publish","type":"post","link":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/","title":{"rendered":"Dalla Spagna un Educational inedito con MIG 2023"},"content":{"rendered":"<p>Qualche anticipazione per un evento eccezionale che, grazie alla Mostra internazionale del Gelato di Longarone, avr\u00e0 luogo nelle giornate di luned\u00ec 27 (nel meraviglioso CastelBrando Hotel, su invito) e, nella sede della fiera, marted\u00ec 28 novembre prossimi con il patrocinio di Artglace, la confederazione delle Associazioni dei gelatieri artigiani d\u2019Europa.<\/p>\n<p>Una delegazione composta da sei tra i migliori e pi\u00f9 celebri professionisti dei mestieri del gusto spagnoli, gelatieri, pasticcieri, cuochi guidata da <strong>Marco Miquel Sirvent<\/strong>, presidente dell\u2019ANHCEA (Associaci\u00f3n Nacional de Heladeros Artesanos), svolger\u00e0 un Educational dal tema<\/p>\n<p><strong>L\u2019ORIGINE E IL RICORDO<\/strong><\/p>\n<p>Un susseguirsi di emozionanti creazioni di gelateria, pasticceria, di cucina ispirate al tema, realizzate in diretta davanti al pubblico e che culmineranno nelle varie degustazioni. A seguire, per dare maggior spessore all\u2019evento, un\u2019amichevole chiacchierata con il pubblico sulle tecniche di lavorazione e motivazioni che hanno ispirato le carriere e le scelte di vita dei professionisti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qualche anticipazione per un evento eccezionale che, grazie alla Mostra internazionale del Gelato di Longarone, avr\u00e0 luogo nelle giornate di luned\u00ec 27 (nel meraviglioso CastelBrando Hotel, su invito) e, nella sede della fiera, marted\u00ec 28 novembre prossimi con il patrocinio di Artglace, la confederazione delle Associazioni dei gelatieri artigiani d\u2019Europa. Una delegazione composta da sei [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8938,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1459,1548],"tags":[],"class_list":["post-8937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","category-novita"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dalla Spagna un Educational inedito con MIG 2023 - MIG - Mostra Internazionale del Gelato Artigianale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dalla Spagna un Educational inedito con MIG 2023 - MIG - Mostra Internazionale del Gelato Artigianale\" \/>\n<meta property=\"og:description\" content=\"Qualche anticipazione per un evento eccezionale che, grazie alla Mostra internazionale del Gelato di Longarone, avr\u00e0 luogo nelle giornate di luned\u00ec 27 (nel meraviglioso CastelBrando Hotel, su invito) e, nella sede della fiera, marted\u00ec 28 novembre prossimi con il patrocinio di Artglace, la confederazione delle Associazioni dei gelatieri artigiani d\u2019Europa. Una delegazione composta da sei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"MIG - Mostra Internazionale del Gelato Artigianale\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-11T07:17:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/11\/Marco-Miquel-ANHCEA-w.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1367\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Longarone Fiere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longarone Fiere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/\"},\"author\":{\"name\":\"Longarone Fiere\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\"},\"headline\":\"Dalla Spagna un Educational inedito con MIG 2023\",\"datePublished\":\"2023-11-11T07:17:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/\"},\"wordCount\":157,\"image\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Marco-Miquel-ANHCEA-w.jpg?fit=1920%2C1367&ssl=1\",\"articleSection\":[\"Eventi\",\"Novit\u00e0\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/\",\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/\",\"name\":\"Dalla Spagna un Educational inedito con MIG 2023 - MIG - Mostra Internazionale del Gelato Artigianale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Marco-Miquel-ANHCEA-w.jpg?fit=1920%2C1367&ssl=1\",\"datePublished\":\"2023-11-11T07:17:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Marco-Miquel-ANHCEA-w.jpg?fit=1920%2C1367&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Marco-Miquel-ANHCEA-w.jpg?fit=1920%2C1367&ssl=1\",\"width\":1920,\"height\":1367,\"caption\":\"Marco Miquel presidente ANHCEA\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/dalla-spagna-un-educational-inedito-con-mig-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dalla Spagna un Educational inedito con MIG 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/\",\"name\":\"MIG - Mostra Internazionale del Gelato Artigianale\",\"description\":\"Longarone Fiere Dolomiti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\",\"name\":\"Longarone Fiere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"caption\":\"Longarone Fiere\"},\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/author\\\/longarone_fiere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dalla Spagna un Educational inedito con MIG 2023 - MIG - Mostra Internazionale del Gelato Artigianale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/","og_locale":"en_US","og_type":"article","og_title":"Dalla Spagna un Educational inedito con MIG 2023 - MIG - Mostra Internazionale del Gelato Artigianale","og_description":"Qualche anticipazione per un evento eccezionale che, grazie alla Mostra internazionale del Gelato di Longarone, avr\u00e0 luogo nelle giornate di luned\u00ec 27 (nel meraviglioso CastelBrando Hotel, su invito) e, nella sede della fiera, marted\u00ec 28 novembre prossimi con il patrocinio di Artglace, la confederazione delle Associazioni dei gelatieri artigiani d\u2019Europa. Una delegazione composta da sei [&hellip;]","og_url":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/","og_site_name":"MIG - Mostra Internazionale del Gelato Artigianale","article_published_time":"2023-11-11T07:17:08+00:00","og_image":[{"width":1920,"height":1367,"url":"https:\/\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/11\/Marco-Miquel-ANHCEA-w.jpg","type":"image\/jpeg"}],"author":"Longarone Fiere","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Longarone Fiere","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/#article","isPartOf":{"@id":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/"},"author":{"name":"Longarone Fiere","@id":"https:\/\/www.mostradelgelato.com\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54"},"headline":"Dalla Spagna un Educational inedito con MIG 2023","datePublished":"2023-11-11T07:17:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/"},"wordCount":157,"image":{"@id":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/11\/Marco-Miquel-ANHCEA-w.jpg?fit=1920%2C1367&ssl=1","articleSection":["Eventi","Novit\u00e0"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/","url":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/","name":"Dalla Spagna un Educational inedito con MIG 2023 - MIG - Mostra Internazionale del Gelato Artigianale","isPartOf":{"@id":"https:\/\/www.mostradelgelato.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/#primaryimage"},"image":{"@id":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/11\/Marco-Miquel-ANHCEA-w.jpg?fit=1920%2C1367&ssl=1","datePublished":"2023-11-11T07:17:08+00:00","author":{"@id":"https:\/\/www.mostradelgelato.com\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54"},"breadcrumb":{"@id":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/#primaryimage","url":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/11\/Marco-Miquel-ANHCEA-w.jpg?fit=1920%2C1367&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/11\/Marco-Miquel-ANHCEA-w.jpg?fit=1920%2C1367&ssl=1","width":1920,"height":1367,"caption":"Marco Miquel presidente ANHCEA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mostradelgelato.com\/en\/dalla-spagna-un-educational-inedito-con-mig-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mostradelgelato.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Dalla Spagna un Educational inedito con MIG 2023"}]},{"@type":"WebSite","@id":"https:\/\/www.mostradelgelato.com\/en\/#website","url":"https:\/\/www.mostradelgelato.com\/en\/","name":"MIG - Mostra Internazionale del Gelato Artigianale","description":"Longarone Fiere Dolomiti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mostradelgelato.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.mostradelgelato.com\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54","name":"Longarone Fiere","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","caption":"Longarone Fiere"},"url":"https:\/\/www.mostradelgelato.com\/en\/author\/longarone_fiere\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/11\/Marco-Miquel-ANHCEA-w.jpg?fit=1920%2C1367&ssl=1","_links":{"self":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/posts\/8937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/comments?post=8937"}],"version-history":[{"count":0,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/posts\/8937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/media\/8938"}],"wp:attachment":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/media?parent=8937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/categories?post=8937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/tags?post=8937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}