{"id":762,"date":"2017-12-02T14:17:00","date_gmt":"2017-12-02T13:17:00","guid":{"rendered":"http:\/\/wpeventime.tchaikovsky.design\/?p=762"},"modified":"2017-12-02T14:17:00","modified_gmt":"2017-12-02T13:17:00","slug":"domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia","status":"publish","type":"post","link":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/","title":{"rendered":"Domani l&#8217;apertura della 58\u00aa MIG con il governatore Luca Zaia"},"content":{"rendered":"<p>Si apre domani, domenica 3 dicembre (ore 10) nel Quartiere di Longarone Fiere la 58^ edizione della\u00a0<strong>MIG<\/strong>, la\u00a0<strong>Mostra Internazionale del Gelato Artigianale<\/strong>, che proseguir\u00e0 sino a\u00a0<strong>mercoled\u00ec 6 dicembre<\/strong>, facendo di Longarone per quattro giornate la capitale mondiale del gelato artigianale. Un\u2019edizione davvero straordinaria per un evento che sempre di pi\u00f9 si presenta come punto di riferimento assoluto del settore. In fiera vi saranno infatti oltre\u00a0<strong>230 marchi aziendali<\/strong>\u00a0(da 16 regioni italiane e 11 Paesi esteri) con la conferma dei leader internazionali in fatto di macchine, attrezzature, semilavorati, materie prime, arredamenti e accessori per la gelateria artigiana. Sul fronte operatori e gelatieri sono attese diverse delegazioni, dalla Spagna alla Polonia, dal Kazakistan al Brasile, e ancora da Azerbaijan, Repubblica Ceca, Slovacchia, Ungheria, Croazia e naturalmente dal Marocco.<\/p>\n<p>La giornata di domani, domenica 3 dicembre entrer\u00e0 subito nel vivo con il taglio del nastro e la cerimonia inaugurale delle 10.30 alla presenza del Governatore della Regione Veneto,\u00a0<strong>Luca Zaia<\/strong>.<\/p>\n<p>Nel corso della cerimonia verr\u00e0 consegnato il premio \u201c<strong>Mastri Gelatieri<\/strong>\u201d alla sua 22. edizione, oltre al 5. premio \u201c<strong>Innovazione MIG Longarone Fiere<\/strong>\u201d, destinato a premiare contenuti fortemente innovativi in termini di tecnologie di lavorazione e di prodotti per la gelateria artigianale. Nel pomeriggio nell\u2019<strong>Area Incontri<\/strong>\u00a0(Padiglione C) a partire dalle 14.00, si terr\u00e0 invece la registrazione della trasmissione\u00a0<strong>In Piazza<\/strong>\u00a0del noto giornalista\u00a0<strong>Luigi Gandi<\/strong>\u00a0che affronter\u00e0 il tema dei \u201c<strong>Nuovi Orizzonti sull\u2019internazionalit\u00e0 del GELATO<\/strong>\u201d con interventi di autorit\u00e0 ed esponenti del mondo del gelato da tutta Europa, Argentina e Brasile.<\/p>\n<p>Sempre in Area Incontri seguir\u00e0 la presentazione curata da\u00a0<strong>Artglace<\/strong>\u00a0delle iniziative promozionali per la\u00a0<strong>6a Giornata Europea del Gelato Artigianale<\/strong>\u00a0e la presentazione del gusto, spettava alla Germania la scelta per il\u00a0<strong>24 marzo 2018<\/strong>, che per tutto il prossimo anno sar\u00e0 realizzato dalle Associazioni di gelatieri d\u2019Europa per promuove questo fantastico riconoscimento della UE.<\/p>\n<p>L\u2019Area Incontri chiuder\u00e0 con la presentazione alle 17.00 del libro-ricerca\u00a0<strong>\u201cI gelatieri bellunesi che conquistarono la penisola iberica\u201d<\/strong>\u00a0a cura di\u00a0<strong>Silvana Molin Pradel<\/strong>.<\/p>\n<p>Mentre in\u00a0<strong>MIG-Arena<\/strong>\u00a0si susseguiranno le presentazioni di pi\u00f9 libri a tema e in particolare alle 13.30 Italian Gourmet ci propone\u00a0<strong>\u201cGelateria per tutte le stagioni\u201d<\/strong>\u00a0con l\u2019intervento dell\u2019autore\u00a0<strong>Paolo Brunelli<\/strong>, segue alle 14.30 Editrade con due volumi, il 2\u00b0 Quaderno di Alice:\u00a0<strong>\u201cNuova dimensione del gelato soft\u201d<\/strong>\u00a0con l\u2019intervento di\u00a0<strong>Alice Vignoli<\/strong>,\u00a0<strong>Antonio Amati<\/strong>\u00a0e\u00a0<strong>Roberto Luraghi<\/strong>, e\u00a0<strong>\u201cFusione Inversa\u201d<\/strong>\u00a0con l\u2019intervento degli autori\u00a0<strong>Pier Paolo Magni<\/strong>\u00a0e\u00a0<strong>Luciana Poliotti<\/strong>, entrambi moderati dall\u2019editore\u00a0<strong>Franco Cesare Puglisi<\/strong>. Rimarr\u00e0 seduta Luciana Poliotti, perch\u00e9 alle 16.00 ci parler\u00e0 del suo romanzo\u00a0<strong>\u201cIl Genio del gelato:\u00a0<\/strong><strong>Francesco Procopio Cut\u00f2, storie d&#8217;amore, di talenti e di alchimia tra Palermo e Parigi\u201d\u00a0<\/strong>di Fausto Lupetti Editore.<\/p>\n<p>Ultimo evento, ma non meno importante, della MIG-Arena vedr\u00e0 la dimostrazione e degustazione del\u00a0<strong>Gelato gusto ITALICO<\/strong>\u00a0alle 17.00 realizzate dai gelatieri\u00a0<strong>Dave Destefano<\/strong>,\u00a0<strong>Gaetano Vincenzi<\/strong>,\u00a0<strong>Pasquale<\/strong>\u00a0<strong>Monteleone<\/strong>,\u00a0<strong>Guido Zandon\u00e0<\/strong>\u00a0<strong>e Francesco Dioletta<\/strong>.<\/p>\n<p>Nel corso della giornata odierna invece come di consueto l\u2019assemblea generale di\u00a0<strong>Artglace<\/strong>, la Confederazione che riunisce le associazioni nazionali di gelatieri dell\u2019UE, e del\u00a0<strong>G.A.<\/strong>, il Comitato nazionale per la difesa e la diffusione del gelato artigianale di produzione propria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si apre domani, domenica 3 dicembre (ore 10) nel Quartiere di Longarone Fiere la 58^ edizione della\u00a0MIG, la\u00a0Mostra Internazionale del Gelato Artigianale, che proseguir\u00e0 sino a\u00a0mercoled\u00ec 6 dicembre, facendo di Longarone per quattro giornate la capitale mondiale del gelato artigianale. Un\u2019edizione davvero straordinaria per un evento che sempre di pi\u00f9 si presenta come punto di [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1359,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1459],"tags":[1556,1432,1551,1547],"class_list":["post-762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventi","tag-artglace","tag-longarone-fiere","tag-maestri-gelatieri","tag-mig-2017"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Domani l&#039;apertura della 58\u00aa MIG con il governatore Luca Zaia - MIG - Mostra Internazionale del Gelato Artigianale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Domani l&#039;apertura della 58\u00aa MIG con il governatore Luca Zaia - MIG - Mostra Internazionale del Gelato Artigianale\" \/>\n<meta property=\"og:description\" content=\"Si apre domani, domenica 3 dicembre (ore 10) nel Quartiere di Longarone Fiere la 58^ edizione della\u00a0MIG, la\u00a0Mostra Internazionale del Gelato Artigianale, che proseguir\u00e0 sino a\u00a0mercoled\u00ec 6 dicembre, facendo di Longarone per quattro giornate la capitale mondiale del gelato artigianale. Un\u2019edizione davvero straordinaria per un evento che sempre di pi\u00f9 si presenta come punto di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/\" \/>\n<meta property=\"og:site_name\" content=\"MIG - Mostra Internazionale del Gelato Artigianale\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-02T13:17:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mostradelgelato.com\/wp-content\/uploads\/2016\/05\/MIG-interni.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Longarone Fiere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longarone Fiere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/\"},\"author\":{\"name\":\"Longarone Fiere\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\"},\"headline\":\"Domani l&#8217;apertura della 58\u00aa MIG con il governatore Luca Zaia\",\"datePublished\":\"2017-12-02T13:17:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/\"},\"wordCount\":521,\"image\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/MIG-interni.jpg?fit=1024%2C610&ssl=1\",\"keywords\":[\"Artglace\",\"Longarone Fiere\",\"Maestri gelatieri\",\"MIG 2017\"],\"articleSection\":[\"Eventi\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/\",\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/\",\"name\":\"Domani l'apertura della 58\u00aa MIG con il governatore Luca Zaia - MIG - Mostra Internazionale del Gelato Artigianale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/MIG-interni.jpg?fit=1024%2C610&ssl=1\",\"datePublished\":\"2017-12-02T13:17:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/MIG-interni.jpg?fit=1024%2C610&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/MIG-interni.jpg?fit=1024%2C610&ssl=1\",\"width\":1024,\"height\":610},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Domani l&#8217;apertura della 58\u00aa MIG con il governatore Luca Zaia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/\",\"name\":\"MIG - Mostra Internazionale del Gelato Artigianale\",\"description\":\"Longarone Fiere Dolomiti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\",\"name\":\"Longarone Fiere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"caption\":\"Longarone Fiere\"},\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/author\\\/longarone_fiere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Domani l'apertura della 58\u00aa MIG con il governatore Luca Zaia - MIG - Mostra Internazionale del Gelato Artigianale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/","og_locale":"en_US","og_type":"article","og_title":"Domani l'apertura della 58\u00aa MIG con il governatore Luca Zaia - MIG - Mostra Internazionale del Gelato Artigianale","og_description":"Si apre domani, domenica 3 dicembre (ore 10) nel Quartiere di Longarone Fiere la 58^ edizione della\u00a0MIG, la\u00a0Mostra Internazionale del Gelato Artigianale, che proseguir\u00e0 sino a\u00a0mercoled\u00ec 6 dicembre, facendo di Longarone per quattro giornate la capitale mondiale del gelato artigianale. Un\u2019edizione davvero straordinaria per un evento che sempre di pi\u00f9 si presenta come punto di [&hellip;]","og_url":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/","og_site_name":"MIG - Mostra Internazionale del Gelato Artigianale","article_published_time":"2017-12-02T13:17:00+00:00","og_image":[{"width":1024,"height":610,"url":"https:\/\/www.mostradelgelato.com\/wp-content\/uploads\/2016\/05\/MIG-interni.jpg","type":"image\/jpeg"}],"author":"Longarone Fiere","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Longarone Fiere","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/#article","isPartOf":{"@id":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/"},"author":{"name":"Longarone Fiere","@id":"https:\/\/www.mostradelgelato.com\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54"},"headline":"Domani l&#8217;apertura della 58\u00aa MIG con il governatore Luca Zaia","datePublished":"2017-12-02T13:17:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/"},"wordCount":521,"image":{"@id":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2016\/05\/MIG-interni.jpg?fit=1024%2C610&ssl=1","keywords":["Artglace","Longarone Fiere","Maestri gelatieri","MIG 2017"],"articleSection":["Eventi"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/","url":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/","name":"Domani l'apertura della 58\u00aa MIG con il governatore Luca Zaia - MIG - Mostra Internazionale del Gelato Artigianale","isPartOf":{"@id":"https:\/\/www.mostradelgelato.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/#primaryimage"},"image":{"@id":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2016\/05\/MIG-interni.jpg?fit=1024%2C610&ssl=1","datePublished":"2017-12-02T13:17:00+00:00","author":{"@id":"https:\/\/www.mostradelgelato.com\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54"},"breadcrumb":{"@id":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/#primaryimage","url":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2016\/05\/MIG-interni.jpg?fit=1024%2C610&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2016\/05\/MIG-interni.jpg?fit=1024%2C610&ssl=1","width":1024,"height":610},{"@type":"BreadcrumbList","@id":"https:\/\/www.mostradelgelato.com\/en\/domani-lapertura-della-58-mig-mostra-internazionale-del-gelato-artigianale-con-il-governatore-luca-zaia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mostradelgelato.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Domani l&#8217;apertura della 58\u00aa MIG con il governatore Luca Zaia"}]},{"@type":"WebSite","@id":"https:\/\/www.mostradelgelato.com\/en\/#website","url":"https:\/\/www.mostradelgelato.com\/en\/","name":"MIG - Mostra Internazionale del Gelato Artigianale","description":"Longarone Fiere Dolomiti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mostradelgelato.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.mostradelgelato.com\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54","name":"Longarone Fiere","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","caption":"Longarone Fiere"},"url":"https:\/\/www.mostradelgelato.com\/en\/author\/longarone_fiere\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2016\/05\/MIG-interni.jpg?fit=1024%2C610&ssl=1","_links":{"self":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/posts\/762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/comments?post=762"}],"version-history":[{"count":0,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/posts\/762\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/media\/1359"}],"wp:attachment":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/media?parent=762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/categories?post=762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/tags?post=762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}