{"id":11540,"date":"2024-05-15T12:37:52","date_gmt":"2024-05-15T10:37:52","guid":{"rendered":"https:\/\/www.mostradelgelato.com\/?p=11540"},"modified":"2024-05-15T12:37:52","modified_gmt":"2024-05-15T10:37:52","slug":"maestro-arte-gelateria-italiana","status":"publish","type":"post","link":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/","title":{"rendered":"Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d"},"content":{"rendered":"<p>Entrer\u00e0 in vigore il prossimo 21 maggio la legge (19 aprile 2024, n. 59) che istituisce il premio nazionale di<strong> \u201cMaestro dell\u2019arte della cucina italiana\u201d<\/strong>. A motivarla il fatto che l\u2019<strong>arte culinaria rappresenta un\u2019eccellenza italiana capace di coniugare artigianalit\u00e0 e creativit\u00e0<\/strong>. Cos\u00ec il Ministero dell\u2019agricoltura, della sovranit\u00e0 alimentare e delle foreste ne sostiene e ne promuove lo sviluppo, volgendo la propria azione istituzionale anche al recupero delle tradizioni e alla valorizzazione delle relative professionalit\u00e0. Il Premio potr\u00e0 essere conferito ai cittadini italiani che si siano \u201c<em><strong>distinti in modo encomiabile nel campo della gastronomia e con la loro opera abbiano esaltato il prestigio della cucina italiana, illustrando la Patria e contribuendo a valorizzare l\u2019eccellenza nazionale<\/strong><\/em>\u201d.<\/p>\n<p>Il premio \u00e8 conferito annualmente dal <strong>Presidente del Consiglio dei ministri<\/strong>, nel limite di uno per ciascuna delle seguenti categorie di merito:<\/p>\n<ul>\n<li><strong>a) gelateria;<\/strong><\/li>\n<li><strong>b) pasticceria;<\/strong><\/li>\n<li><strong>c) cucina;<\/strong><\/li>\n<li><strong>d) vitivinicoltura;<\/strong><\/li>\n<li><strong>e) olivicoltura;<\/strong><\/li>\n<li><strong>f) arte casearia.<\/strong><\/li>\n<\/ul>\n<p>Il premio \u00e8 costituito da una<strong> medaglia di bronzo<\/strong> che presenta, da un lato, l\u2019emblema della Repubblica italiana e, dall\u2019altro lato, in ragione dell\u2019appartenenza a una delle categorie di merito, una delle seguenti diciture:<\/p>\n<ul>\n<li><strong>a) \u00abMaestro dell\u2019arte della gelateria italiana\u00bb;<\/strong><\/li>\n<li><strong>b) \u00abMaestro dell\u2019arte della pasticceria italiana\u00bb;<\/strong><\/li>\n<li><strong>c) \u00abMaestro dell\u2019arte della cucina italiana\u00bb;<\/strong><\/li>\n<li><strong>d) \u00abMaestro dell\u2019arte vitivinicola italiana\u00bb;<\/strong><\/li>\n<li><strong>e) \u00abMaestro dell\u2019arte olivicola italiana\u00bb;<\/strong><\/li>\n<li><strong>f) \u00abMaestro dell\u2019arte casearia italiana\u00bb.<\/strong><\/li>\n<\/ul>\n<p>Potranno essere candidati al premio i cittadini italiani con i seguenti requisiti:<\/p>\n<ul>\n<li>a) avere concluso un percorso formativo pluriennale nel settore di riferimento;<\/li>\n<li>b) avere maturato almeno quindici anni di comprovata e riconosciuta esperienza nel settore di riferimento;<\/li>\n<li>c) avere tenuto una condotta civile e sociale irreprensibile;<\/li>\n<li>d) avere adempiuto agli obblighi tributari e previdenziali.<\/li>\n<\/ul>\n<p>Dal testo pubblicato in Gazzetta Ufficiale risulta che le candidature dovranno essere inviate alla Presidenza del Consiglio dei ministri entro il 30 aprile di ciascun anno. Mentre per la prima applicazione, il Presidente del Consiglio dei ministri, entro sessanta giorni dalla data di entrata in vigore della presente legge, conferir\u00e0 sei premi di Maestro dell&#8217;arte della cucina italiana, uno per ciascuna delle categorie. Questi primi sei Maestri andranno a costituire il comitato di selezione per il prossimo triennio.<\/p>\n<p>Da sottolineare che agli insigniti del premio potranno essere conferiti incarichi di esperto negli Istituti\u00a0\u00a0 professionali per l&#8217;enogastronomia e l&#8217;ospitalit\u00e0&#8217; alberghiera in deroga ai requisiti previsti dal decreto legislativo 30 marzo 2001, n. 165.<\/p>\n<p>Il testo integrale pubblicato sulla Gazzetta Ufficiale \u00e8 disponibile al seguente link:<br \/>\n<a href=\"https:\/\/www.gazzettaufficiale.it\/eli\/id\/2024\/05\/06\/24G00075\/sg\">https:\/\/www.gazzettaufficiale.it\/eli\/id\/2024\/05\/06\/24G00075\/sg<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entrer\u00e0 in vigore il prossimo 21 maggio la legge (19 aprile 2024, n. 59) che istituisce il premio nazionale di \u201cMaestro dell\u2019arte della cucina italiana\u201d. A motivarla il fatto che l\u2019arte culinaria rappresenta un\u2019eccellenza italiana capace di coniugare artigianalit\u00e0 e creativit\u00e0. Cos\u00ec il Ministero dell\u2019agricoltura, della sovranit\u00e0 alimentare e delle foreste ne sostiene e ne [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11541,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1548],"tags":[2166,2167,2168,2169],"class_list":["post-11540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita","tag-arte-gelateria-italiana","tag-cucina-italiana","tag-maestro","tag-premio"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d - MIG - Mostra Internazionale del Gelato Artigianale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d - MIG - Mostra Internazionale del Gelato Artigianale\" \/>\n<meta property=\"og:description\" content=\"Entrer\u00e0 in vigore il prossimo 21 maggio la legge (19 aprile 2024, n. 59) che istituisce il premio nazionale di \u201cMaestro dell\u2019arte della cucina italiana\u201d. A motivarla il fatto che l\u2019arte culinaria rappresenta un\u2019eccellenza italiana capace di coniugare artigianalit\u00e0 e creativit\u00e0. Cos\u00ec il Ministero dell\u2019agricoltura, della sovranit\u00e0 alimentare e delle foreste ne sostiene e ne [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/\" \/>\n<meta property=\"og:site_name\" content=\"MIG - Mostra Internazionale del Gelato Artigianale\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-15T10:37:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mostradelgelato.com\/wp-content\/uploads\/2024\/05\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1590\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Longarone Fiere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longarone Fiere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/\"},\"author\":{\"name\":\"Longarone Fiere\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\"},\"headline\":\"Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d\",\"datePublished\":\"2024-05-15T10:37:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/\"},\"wordCount\":421,\"image\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg?fit=2560%2C1590&ssl=1\",\"keywords\":[\"Arte Gelateria Italiana\",\"Cucina Italiana\",\"Maestro\",\"Premio\"],\"articleSection\":[\"Novit\u00e0\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/\",\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/\",\"name\":\"Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d - MIG - Mostra Internazionale del Gelato Artigianale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg?fit=2560%2C1590&ssl=1\",\"datePublished\":\"2024-05-15T10:37:52+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg?fit=2560%2C1590&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg?fit=2560%2C1590&ssl=1\",\"width\":2560,\"height\":1590,\"caption\":\"Premio Maestro dell\u2019arte della gelateria italiana - in foto gelato yogurt variegato fragola\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/maestro-arte-gelateria-italiana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/\",\"name\":\"MIG - Mostra Internazionale del Gelato Artigianale\",\"description\":\"Longarone Fiere Dolomiti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\",\"name\":\"Longarone Fiere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"caption\":\"Longarone Fiere\"},\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/en\\\/author\\\/longarone_fiere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d - MIG - Mostra Internazionale del Gelato Artigianale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/","og_locale":"en_US","og_type":"article","og_title":"Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d - MIG - Mostra Internazionale del Gelato Artigianale","og_description":"Entrer\u00e0 in vigore il prossimo 21 maggio la legge (19 aprile 2024, n. 59) che istituisce il premio nazionale di \u201cMaestro dell\u2019arte della cucina italiana\u201d. A motivarla il fatto che l\u2019arte culinaria rappresenta un\u2019eccellenza italiana capace di coniugare artigianalit\u00e0 e creativit\u00e0. Cos\u00ec il Ministero dell\u2019agricoltura, della sovranit\u00e0 alimentare e delle foreste ne sostiene e ne [&hellip;]","og_url":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/","og_site_name":"MIG - Mostra Internazionale del Gelato Artigianale","article_published_time":"2024-05-15T10:37:52+00:00","og_image":[{"width":2560,"height":1590,"url":"https:\/\/www.mostradelgelato.com\/wp-content\/uploads\/2024\/05\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg","type":"image\/jpeg"}],"author":"Longarone Fiere","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Longarone Fiere","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/#article","isPartOf":{"@id":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/"},"author":{"name":"Longarone Fiere","@id":"https:\/\/www.mostradelgelato.com\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54"},"headline":"Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d","datePublished":"2024-05-15T10:37:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/"},"wordCount":421,"image":{"@id":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2024\/05\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg?fit=2560%2C1590&ssl=1","keywords":["Arte Gelateria Italiana","Cucina Italiana","Maestro","Premio"],"articleSection":["Novit\u00e0"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/","url":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/","name":"Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d - MIG - Mostra Internazionale del Gelato Artigianale","isPartOf":{"@id":"https:\/\/www.mostradelgelato.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/#primaryimage"},"image":{"@id":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2024\/05\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg?fit=2560%2C1590&ssl=1","datePublished":"2024-05-15T10:37:52+00:00","author":{"@id":"https:\/\/www.mostradelgelato.com\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54"},"breadcrumb":{"@id":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/#primaryimage","url":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2024\/05\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg?fit=2560%2C1590&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2024\/05\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg?fit=2560%2C1590&ssl=1","width":2560,"height":1590,"caption":"Premio Maestro dell\u2019arte della gelateria italiana - in foto gelato yogurt variegato fragola"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mostradelgelato.com\/en\/maestro-arte-gelateria-italiana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mostradelgelato.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Anche la gelateria nel Premio di \u201cMaestro dell\u2019arte della cucina italiana\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.mostradelgelato.com\/en\/#website","url":"https:\/\/www.mostradelgelato.com\/en\/","name":"MIG - Mostra Internazionale del Gelato Artigianale","description":"Longarone Fiere Dolomiti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mostradelgelato.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.mostradelgelato.com\/en\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54","name":"Longarone Fiere","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","caption":"Longarone Fiere"},"url":"https:\/\/www.mostradelgelato.com\/en\/author\/longarone_fiere\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2024\/05\/Gelato-Yogurt-variegato-fragola-scaled-1.jpg?fit=2560%2C1590&ssl=1","_links":{"self":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/posts\/11540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/comments?post=11540"}],"version-history":[{"count":0,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/posts\/11540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/media\/11541"}],"wp:attachment":[{"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/media?parent=11540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/categories?post=11540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/en\/wp-json\/wp\/v2\/tags?post=11540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}