{"id":8640,"date":"2023-10-30T14:36:43","date_gmt":"2023-10-30T13:36:43","guid":{"rendered":"https:\/\/www.mostradelgelato.com\/?p=8640"},"modified":"2023-10-30T14:36:43","modified_gmt":"2023-10-30T13:36:43","slug":"a-mig-2023-consigli-per-il-successo-in-gelateria","status":"publish","type":"post","link":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/","title":{"rendered":"A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA"},"content":{"rendered":"<p>Mancano ormai meno di 30 giorni all\u2019apertura della 63. edizione di MIG \u2013 Mostra Internazionale del Gelato Artigianale in programma a Longarone dal 26 al 29 novembre prossimi.<\/p>\n<p>L\u2019evento si presenta ancora pi\u00f9 interessante per i gelatieri in quanto, a fianco alla parte espositiva, completa in ogni settore merceologico che rimane l\u2019aspetto principale, sono previsti dei momenti di formazione-informazione assai utili per la gestione di una gelateria di successo.<\/p>\n<p>Gli incontri, la cui partecipazione \u00e8 gratuita, riguardano, in particolare, <strong>la definizione del listino prezzi<\/strong> e le opportunit\u00e0 di ampliare l\u2019offerta delle gelaterie con <strong>l\u2019inserimento di prodotti di cioccolateria<\/strong> che consentano anche di allungare la stagione di apertura.<\/p>\n<p>Un listino prezzi aggiornato, in grado di coprire i costi aziendali e garantire un margine per il titolare e rimanere competitivi, non pu\u00f2 essere frutto di sola immaginazione o di un adeguamento a quanto fanno altri colleghi. \u201c<em>Il listino prezzi non \u00e8 solo un elenco di numeri<\/em> \u2013 afferma <strong>Giacomo Tonelli<\/strong>, noto Business Coach specializzato nel settore delle Gelaterie Artigianali, che terr\u00e0 gli incontri &#8211; <em>ma un potente strumento di marketing e posizionamento. La sua stesura richiede una profonda comprensione del mercato, dei costi e del valore percepito dal cliente<\/em>\u201d.<\/p>\n<p>\u201c<em>Dalla nostra quotidiana esperienza rileviamo come l\u2019inserimento della cioccolateria in gelateria sia una tendenza sempre pi\u00f9 diffusa<\/em> \u2013 spiega <strong>Angela De Luca<\/strong>, direttrice e docente di <strong>Quinta Forma<\/strong> \u2013 <em>Sono sempre di pi\u00f9 le gelaterie che si interessano al mondo del cioccolato.\u00a0 Cioccolato e gelato, infatti, si abbinano molto bene tra loro sia dal punto di vista del brand, sia per questioni di stagionalit\u00e0. Inserire una linea di cioccolato non richiede poi un grandissimo investimento iniziale. Con una spesa relativamente bassa si pu\u00f2 gi\u00e0 introdurre una produzione di cioccolato di notevole dimensione e qualit\u00e0<\/em>.\u201d<\/p>\n<p>Mentre, <strong>luned\u00ec 27 novembre<\/strong>, ci sar\u00e0 un focus sulla \u201c<strong>Gelateria del Futuro<\/strong>\u201d con una particolare attenzione ai molteplici aspetti della sostenibilit\u00e0, partendo dai materiali fino all\u2019approfondimento di soluzioni innovative in grado di coniugare risparmio e qualit\u00e0 allo stesso tempo, grazie all\u2019intervento dell\u2019architetto <strong>Daniele Menichini<\/strong>.<\/p>\n<p>Oltre a questo, nella giornata di <strong>marted\u00ec 28 novembre<\/strong>, sar\u00e0 di sicuro interesse la presentazione di alcune <strong>storie ed esperienze di successo<\/strong> che verranno illustrate da noti gelatieri. Una iniziativa molto utile a tutti per prendere spunti e fare riflessioni su iniziative che possono essere intraprese per la gestione e promozione anche della propria gelateria.<\/p>\n<p>Ma, come detto in apertura, in una fiera l\u2019attenzione \u00e8 rivolta soprattutto alle aziende e la MIG con la sua storia lunga 63 anni, con alcuni di questi marchi, ha instaurato rapporti che vanno oltre il puro aspetto commerciale.<\/p>\n<p>Ecco cosa ha dichiarato, al proposito, <strong>Giovanni Galli<\/strong>, Business Director di IceTeam 1927: \u201c<em>Cattabriga \u00e8 una storica presenza alla Mostra Internazionale del Gelato di Longarone fin dal 1959. Crediamo fermamente sia una splendida opportunit\u00e0 di incontro per l\u2019intero settore ma c\u2019\u00e8 di pi\u00f9. Se \u00e8 vero che il Settore \u00e8 fatto da aziende, \u00e8 altres\u00ec vero che la loro forza stia nelle persone, quelle guidate dalla passione per questo mondo e, alla MIG, la storia del gelato si respira nell\u2019aria, si legge negli occhi di chi quella storia l\u2019ha vissuta. Nel 2022 ci siamo aggiudicati il premio \u201cMIG Green per la migliore innovazione sostenibile\u201d grazie alla Vario Icona Hybrid, una macchina combinata che sfrutta il nostro brevetto per la condensazione ibrida. Cosa presenteremo quest\u2019anno? \u2026venite a trovarci<\/em>.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mancano ormai meno di 30 giorni all\u2019apertura della 63. edizione di MIG \u2013 Mostra Internazionale del Gelato Artigianale in programma a Longarone dal 26 al 29 novembre prossimi. L\u2019evento si presenta ancora pi\u00f9 interessante per i gelatieri in quanto, a fianco alla parte espositiva, completa in ogni settore merceologico che rimane l\u2019aspetto principale, sono previsti [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8641,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1548],"tags":[1969,2045,2046,1896,2047,1572,1997,2048,1981,1818,1643,1970],"class_list":["post-8640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novita","tag-angela-de-luca","tag-cattabriga","tag-daniele-menichini","tag-gelateria","tag-gelateria-del-futuro","tag-gelato-artigianale","tag-giacomo-tonelli","tag-iceteam1927","tag-mig-2023","tag-mig-green","tag-mig-longarone","tag-quinta-forma"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA - MIG - Mostra Internazionale del Gelato Artigianale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA - MIG - Mostra Internazionale del Gelato Artigianale\" \/>\n<meta property=\"og:description\" content=\"Mancano ormai meno di 30 giorni all\u2019apertura della 63. edizione di MIG \u2013 Mostra Internazionale del Gelato Artigianale in programma a Longarone dal 26 al 29 novembre prossimi. L\u2019evento si presenta ancora pi\u00f9 interessante per i gelatieri in quanto, a fianco alla parte espositiva, completa in ogni settore merceologico che rimane l\u2019aspetto principale, sono previsti [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/\" \/>\n<meta property=\"og:site_name\" content=\"MIG - Mostra Internazionale del Gelato Artigianale\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-30T13:36:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/10\/Premio-green-innovazione-2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1848\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Longarone Fiere\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Longarone Fiere\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/\"},\"author\":{\"name\":\"Longarone Fiere\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\"},\"headline\":\"A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA\",\"datePublished\":\"2023-10-30T13:36:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/\"},\"wordCount\":557,\"image\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Premio-green-innovazione-2022.jpg?fit=1848%2C1080&ssl=1\",\"keywords\":[\"Angela De Luca\",\"Cattabriga\",\"Daniele Menichini\",\"Gelateria\",\"Gelateria del Futuro\",\"Gelato Artigianale\",\"Giacomo Tonelli\",\"IceTeam1927\",\"MIG 2023\",\"MIG Green\",\"MIG Longarone\",\"Quinta Forma\"],\"articleSection\":[\"Novit\u00e0\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/\",\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/\",\"name\":\"A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA - MIG - Mostra Internazionale del Gelato Artigianale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Premio-green-innovazione-2022.jpg?fit=1848%2C1080&ssl=1\",\"datePublished\":\"2023-10-30T13:36:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Premio-green-innovazione-2022.jpg?fit=1848%2C1080&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/www.mostradelgelato.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/Premio-green-innovazione-2022.jpg?fit=1848%2C1080&ssl=1\",\"width\":1848,\"height\":1080,\"caption\":\"Premio green innovazione 2022 a Iceteam1927 cattabriga\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/a-mig-2023-consigli-per-il-successo-in-gelateria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/\",\"name\":\"MIG - Mostra Internazionale del Gelato Artigianale\",\"description\":\"Longarone Fiere Dolomiti\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/#\\\/schema\\\/person\\\/2ce2f615148903aec7fe53b6cc9b5d54\",\"name\":\"Longarone Fiere\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g\",\"caption\":\"Longarone Fiere\"},\"url\":\"https:\\\/\\\/www.mostradelgelato.com\\\/de\\\/author\\\/longarone_fiere\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA - MIG - Mostra Internazionale del Gelato Artigianale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/","og_locale":"de_DE","og_type":"article","og_title":"A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA - MIG - Mostra Internazionale del Gelato Artigianale","og_description":"Mancano ormai meno di 30 giorni all\u2019apertura della 63. edizione di MIG \u2013 Mostra Internazionale del Gelato Artigianale in programma a Longarone dal 26 al 29 novembre prossimi. L\u2019evento si presenta ancora pi\u00f9 interessante per i gelatieri in quanto, a fianco alla parte espositiva, completa in ogni settore merceologico che rimane l\u2019aspetto principale, sono previsti [&hellip;]","og_url":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/","og_site_name":"MIG - Mostra Internazionale del Gelato Artigianale","article_published_time":"2023-10-30T13:36:43+00:00","og_image":[{"width":1848,"height":1080,"url":"https:\/\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/10\/Premio-green-innovazione-2022.jpg","type":"image\/jpeg"}],"author":"Longarone Fiere","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Longarone Fiere","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/#article","isPartOf":{"@id":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/"},"author":{"name":"Longarone Fiere","@id":"https:\/\/www.mostradelgelato.com\/de\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54"},"headline":"A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA","datePublished":"2023-10-30T13:36:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/"},"wordCount":557,"image":{"@id":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/10\/Premio-green-innovazione-2022.jpg?fit=1848%2C1080&ssl=1","keywords":["Angela De Luca","Cattabriga","Daniele Menichini","Gelateria","Gelateria del Futuro","Gelato Artigianale","Giacomo Tonelli","IceTeam1927","MIG 2023","MIG Green","MIG Longarone","Quinta Forma"],"articleSection":["Novit\u00e0"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/","url":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/","name":"A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA - MIG - Mostra Internazionale del Gelato Artigianale","isPartOf":{"@id":"https:\/\/www.mostradelgelato.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/#primaryimage"},"image":{"@id":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/10\/Premio-green-innovazione-2022.jpg?fit=1848%2C1080&ssl=1","datePublished":"2023-10-30T13:36:43+00:00","author":{"@id":"https:\/\/www.mostradelgelato.com\/de\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54"},"breadcrumb":{"@id":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/#primaryimage","url":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/10\/Premio-green-innovazione-2022.jpg?fit=1848%2C1080&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/10\/Premio-green-innovazione-2022.jpg?fit=1848%2C1080&ssl=1","width":1848,"height":1080,"caption":"Premio green innovazione 2022 a Iceteam1927 cattabriga"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mostradelgelato.com\/de\/a-mig-2023-consigli-per-il-successo-in-gelateria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mostradelgelato.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"A MIG 2023 CONSIGLI PER IL SUCCESSO IN GELATERIA"}]},{"@type":"WebSite","@id":"https:\/\/www.mostradelgelato.com\/de\/#website","url":"https:\/\/www.mostradelgelato.com\/de\/","name":"MIG - Mostra Internazionale del Gelato Artigianale","description":"Longarone Fiere Dolomiti","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mostradelgelato.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.mostradelgelato.com\/de\/#\/schema\/person\/2ce2f615148903aec7fe53b6cc9b5d54","name":"Longarone Fiere","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/960b08cc69204d10cd0c0d63246fedce35e46c9af83da7a1ea14285de9be3251?s=96&d=mm&r=g","caption":"Longarone Fiere"},"url":"https:\/\/www.mostradelgelato.com\/de\/author\/longarone_fiere\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.mostradelgelato.com\/wp-content\/uploads\/2023\/10\/Premio-green-innovazione-2022.jpg?fit=1848%2C1080&ssl=1","_links":{"self":[{"href":"https:\/\/www.mostradelgelato.com\/de\/wp-json\/wp\/v2\/posts\/8640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mostradelgelato.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mostradelgelato.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/de\/wp-json\/wp\/v2\/comments?post=8640"}],"version-history":[{"count":0,"href":"https:\/\/www.mostradelgelato.com\/de\/wp-json\/wp\/v2\/posts\/8640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/de\/wp-json\/wp\/v2\/media\/8641"}],"wp:attachment":[{"href":"https:\/\/www.mostradelgelato.com\/de\/wp-json\/wp\/v2\/media?parent=8640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/de\/wp-json\/wp\/v2\/categories?post=8640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mostradelgelato.com\/de\/wp-json\/wp\/v2\/tags?post=8640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}